{"id":26261,"date":"2026-05-13T12:06:28","date_gmt":"2026-05-13T10:06:28","guid":{"rendered":"https:\/\/www.austriacult.roma.it\/?post_type=tribe_events&#038;p=26261"},"modified":"2026-05-13T12:08:08","modified_gmt":"2026-05-13T10:08:08","slug":"focus-friedl-vom-groller","status":"publish","type":"tribe_events","link":"https:\/\/www.austriacult.roma.it\/de\/veranstaltung\/fokus-friedl-vom-groller\/","title":{"rendered":"FOKUS FRIEDL VOM GR\u00d6LLER"},"content":{"rendered":"<p><\/p>\n<p>Die 62. Austragung des Pesaro Film Fest legt einen Fokus auf <strong>Friedl vom Gr\u00f6ller<\/strong>, der es gelungen ist, in relativ kurzer Zeit ein umfangreiches filmisches Werk zu schaffen: bis heute rund achtzig Filme, wovon die meisten ab dem Jahr 2000 entstanden sind.<\/p>\n<p>Wie im Katalog der Internationalen Ausstellung des Neuen Kinos zu lesen ist,\u00ab [\u2026] ihr Interesse f\u00fcr die Wiederholung und die Abwandlung sowie die Erforschung neuer Richtungen innerhalb von rigoros definierten Parametern erlauben ihr eine besondere Reflexion der Beziehung zwischen Fotografie und Kino zu entwickeln, zwischen Subjekt und Objekt, Individuum und Welt. Letztlich eine Analyse, eine Reflexion \u00fcber die Identit\u00e4t und ihre vielen Verwandlungen. [\u2026] Ihre zwei- bis dreimin\u00fctigen Aufnahmen markieren den \u00dcbergang von Fotografie zur Aufzeichnung von verstreichender Zeit, wobei das Aufkommen und Sich-Aufl\u00f6sen von Emotionen im Mittelpunkt steht. [\u2026] Die Oberfl\u00e4chen der realen Welt, die Gesichter und die K\u00f6rper von Freunden, Bekannten, K\u00fcnstlerinnen und Familienangeh\u00f6rigen der Regisseurin, werden so Objekte einer \u201eausgedehnten Vision\u201c, die, wenn wir uns darauf einlassen, teilzuhaben, die Spuren des Unsichtbaren ersichtlich, sp\u00fcrbar, und teilweise sogar interpretierbar macht. Die diversen sozialen und \u00e4sthetischen Codes erkundend, [\u2026], hat Friedl vom Gr\u00f6ller ihre Aufmerksamkeit immer auf die Beziehung zwischen Cineastin und gefilmten Subjekt gelegt, sowie auf die schillernde Identit\u00e4t, die letzteres je nach Kontext einnehmen kann. [\u2026] Ihr Kino ist eines, in welchem Bewegung und Fotografie fortw\u00e4hrend miteinander verflochten sind und in dem die Auseinandersetzung mit Zeit, Verg\u00e4nglichkeit und dem Altern eine Konstante darstellt. Friedl vom Gr\u00f6llers Kino konfrontiert die Zuschauenden somit mit dem eigenen Spiegelbild im Spiegel des anderen.\u00bb<\/p>\n<p>Lesen Sie hier das<span style=\"text-decoration: underline;\"><span style=\"color: #0000ff; text-decoration: underline;\"> <a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/www.austriacult.roma.it\/wp-content\/uploads\/2026\/05\/intervista-eng_ita-VOM-GROLLER.docx\">Interview<\/a>\u00a0<\/span><\/span>(in italienischer und englischer Sprache), gef\u00fchrt von Cecilia Ermini und Stefano Miraglia<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Friedl vom Gr\u00f6ller <\/strong><\/p>\n<p>Geboren 1946 in London verbrachte sie ihre Kindheit zwischen Wien und Berlin. Von 1965 bis 1969 studierte sie Fotografie an der Akademie der bildenden K\u00fcnste Wien. Vom Gr\u00f6ller drehte 80 Filme und arbeitet dabei mit 16-mm-Film (beinahe immer in schwarz-wei\u00df und \u00fcblicherweise ohne Ton), wobei sie 30 Meter lange Spulen und eine Filmkamera mit Handaufzug einsetzt. Kein Drehbuch, keine Assistenz, keine Postproduktion; die Aufnahmen werden meist direkt in der Kamera geschnitten. 1990 gr\u00fcndete und leitete sie die Schule f\u00fcr k\u00fcnstlerische Fotografie in Wien. 2006 folgte die Gr\u00fcndung der Schule f\u00fcr Unabh\u00e4ngigen Film Wien, deren Leitung sie bis heute innehat.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><em>Informationen zum Event und Programm <\/em><\/span><\/p>\n<p><a href=\"https:\/\/www.pesarofilmfest.it\/en\/\">Home &#8211; Mostra Internazionale del Nuovo Cinema &#8211; Pesaro Film Festival<\/a><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<\/p>\n<p>Die 62. Austragung des Pesaro Film Fest legt einen Fokus auf Friedl vom Gr\u00f6ller, der es gelungen ist, in relativ kurzer Zeit ein umfangreiches filmisches Werk zu schaffen: bis heute rund achtzig Filme, wovon die meisten ab dem Jahr 2000 entstanden sind.<\/p>\n<p>Wie im Katalog der Internationalen Ausstellung des Neuen Kinos zu lesen ist,\u00ab [\u2026] ihr Interesse f\u00fcr die Wiederholung und die Abwandlung sowie die Erforschung neuer Richtungen innerhalb von rigoros definierten Parametern erlauben ihr eine besondere Reflexion der Beziehung zwischen [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":26263,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"tribe_events_cat":[8],"class_list":["post-26261","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-kino","cat_kino"],"_links":{"self":[{"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tribe_events\/26261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/comments?post=26261"}],"version-history":[{"count":3,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tribe_events\/26261\/revisions"}],"predecessor-version":[{"id":26268,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tribe_events\/26261\/revisions\/26268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/media\/26263"}],"wp:attachment":[{"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/media?parent=26261"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tags?post=26261"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.austriacult.roma.it\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=26261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}